{"id":28614,"date":"2021-02-15T09:37:28","date_gmt":"2021-02-15T08:37:28","guid":{"rendered":"https:\/\/efem.es\/cursos\/?post_type=product&#038;p=28614"},"modified":"2025-11-22T17:36:10","modified_gmt":"2025-11-22T16:36:10","slug":"marketing-en-redes-sociales","status":"publish","type":"product","link":"https:\/\/efem.es\/cursos\/marketing-en-redes-sociales\/","title":{"rendered":"Marketing en Redes Sociales e Implantaci\u00f3n del Negocio Electr\u00f3nico"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"28614\" class=\"elementor elementor-28614\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22bddb45 e-grid e-con-boxed e-con e-child\" data-id=\"22bddb45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-704286d elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"704286d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tModalidad Online\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDisponible APP M\u00f3vil\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67865b9f elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"67865b9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-check\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 64h-48V12c0-6.627-5.373-12-12-12h-40c-6.627 0-12 5.373-12 12v52H160V12c0-6.627-5.373-12-12-12h-40c-6.627 0-12 5.373-12 12v52H48C21.49 64 0 85.49 0 112v352c0 26.51 21.49 48 48 48h352c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm-6 400H54a6 6 0 0 1-6-6V160h352v298a6 6 0 0 1-6 6zm-52.849-200.65L198.842 404.519c-4.705 4.667-12.303 4.637-16.971-.068l-75.091-75.699c-4.667-4.705-4.637-12.303.068-16.971l22.719-22.536c4.705-4.667 12.303-4.637 16.97.069l44.104 44.461 111.072-110.181c4.705-4.667 12.303-4.637 16.971.068l22.536 22.718c4.667 4.705 4.636 12.303-.069 16.97z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t3 Meses de Duraci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t60 Horas Lectivas\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-195dca13 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"195dca13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-certificate\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M458.622 255.92l45.985-45.005c13.708-12.977 7.316-36.039-10.664-40.339l-62.65-15.99 17.661-62.015c4.991-17.838-11.829-34.663-29.661-29.671l-61.994 17.667-15.984-62.671C337.085.197 313.765-6.276 300.99 7.228L256 53.57 211.011 7.229c-12.63-13.351-36.047-7.234-40.325 10.668l-15.984 62.671-61.995-17.667C74.87 57.907 58.056 74.738 63.046 92.572l17.661 62.015-62.65 15.99C.069 174.878-6.31 197.944 7.392 210.915l45.985 45.005-45.985 45.004c-13.708 12.977-7.316 36.039 10.664 40.339l62.65 15.99-17.661 62.015c-4.991 17.838 11.829 34.663 29.661 29.671l61.994-17.667 15.984 62.671c4.439 18.575 27.696 24.018 40.325 10.668L256 458.61l44.989 46.001c12.5 13.488 35.987 7.486 40.325-10.668l15.984-62.671 61.994 17.667c17.836 4.994 34.651-11.837 29.661-29.671l-17.661-62.015 62.65-15.99c17.987-4.302 24.366-27.367 10.664-40.339l-45.984-45.004z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tT\u00edtulo Final\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUna vez completado el curso se obtiene el certificado\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62f68026 e-flex e-con-boxed e-con e-parent\" data-id=\"62f68026\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9bd0ba elementor-widget elementor-widget-text-editor\" data-id=\"f9bd0ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Implanta una tienda online y ll\u00e9vala al \u00e9xito con el uso de t\u00e9cnicas de venta y estrategias de marketing en redes sociales<\/h3><p>Con la llegada de las redes sociales se ha producido una revoluci\u00f3n en la comunicaci\u00f3n. Estos medios son una gran opci\u00f3n para las empresas a la hora de darse a conocer y presentar sus productos al p\u00fablico.\u00a0 Adem\u00e1s, combinado con la presencia de una tienda online, puede marcar la diferencia entre \u00e9xito o fracaso de un proyecto.<\/p><p>El Curso de Marketing en Redes Sociales e Implantaci\u00f3n del Negocio Electr\u00f3nico est\u00e1 divido en tres \u00e1reas tem\u00e1ticas: Marketing en Redes Sociales, Comercio Electr\u00f3nico y T\u00e9cnicas de Venta<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3338e1 elementor-widget elementor-widget-eael-adv-tabs\" data-id=\"b3338e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-adv-tabs.default\">\n\t\t\t\t\t        <div data-scroll-on-click=\"no\" data-scroll-speed=\"300\" id=\"eael-advance-tabs-b3338e1\" class=\"eael-advance-tabs eael-tabs-horizontal eael-tab-auto-active \" data-tabid=\"b3338e1\">\n            <div class=\"eael-tabs-nav \">\n                <ul class=\"eael-tab-inline-icon\" role=\"tablist\">\n                                            <li id=\"presentacin\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"presentacin-tab\" aria-expanded=\"false\">\n                            \n                                                                <svg class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >PRESENTACI\u00d3N<\/span>                            \n                                                    <\/li>\n                                            <li id=\"temario\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"temario-tab\" aria-expanded=\"false\">\n                            \n                                                                <svg class=\"e-font-icon-svg e-fas-book-open\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M542.22 32.05c-54.8 3.11-163.72 14.43-230.96 55.59-4.64 2.84-7.27 7.89-7.27 13.17v363.87c0 11.55 12.63 18.85 23.28 13.49 69.18-34.82 169.23-44.32 218.7-46.92 16.89-.89 30.02-14.43 30.02-30.66V62.75c.01-17.71-15.35-31.74-33.77-30.7zM264.73 87.64C197.5 46.48 88.58 35.17 33.78 32.05 15.36 31.01 0 45.04 0 62.75V400.6c0 16.24 13.13 29.78 30.02 30.66 49.49 2.6 149.59 12.11 218.77 46.95 10.62 5.35 23.21-1.94 23.21-13.46V100.63c0-5.29-2.62-10.14-7.27-12.99z\"><\/path><\/svg>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >TEMARIO<\/span>                            \n                                                    <\/li>\n                                            <li id=\"solicita-informacin\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"solicita-informacin-tab\" aria-expanded=\"false\">\n                            \n                                                                <svg class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >SOLICITA INFORMACI\u00d3N<\/span>                            \n                                                    <\/li>\n                    \n                                  <\/ul>\n            <\/div>\n            \n            <div class=\"eael-tabs-content\">\n\t\t        \n                    <div id=\"presentacin-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"presentacin-tab\">\n\t\t\t\t        <h2>Objetivos<\/h2><p>Los objetivos del Curso de Marketing en Redes Sociales e Implantaci\u00f3n del Negocio Electr\u00f3nico son los siguientes:<\/p><ul><li>Establecer las pautas para que las empresas incrementen los beneficios que obtienen del uso de Internet mediante la aplicaci\u00f3n de t\u00e9cnicas que mejoren sus comunicaciones, la captaci\u00f3n y fidelizaci\u00f3n de clientes, la b\u00fasqueda de informaci\u00f3n, el an\u00e1lisis de la competencia, el posicionamiento de la empresa, la marca y sus productos o servicios, etc.<\/li><li>Conocer las Redes Sociales desde un punto de vista empresarial y como tener presencia en canales 2.0.<\/li><li>Medir la rentabilidad de las estrategias en Redes Sociales.<\/li><li>Conocer como promocionar las ventas mediante el uso de las principales Redes Sociales (Facebook, Twitter, YouTube,\u2026).<\/li><li>Aplicaci\u00f3n de t\u00e9cnicas de marketing mediante el uso del marketing mobile y el marketing viral.<\/li><li>Caracter\u00edsticas principales que debe cumplir un Community Manager. Formaci\u00f3n para la implantaci\u00f3n de negocio electr\u00f3nico: se tratan conceptos fundamentales de lo que es el comercio electr\u00f3nico (e-comerce) pero con una caracter\u00edstica especial que lo convierte en un curso realmente pr\u00e1ctico.<\/li><li>Adquirir habilidades orientadas al uso de herramientas \u00fatiles en el comercio electr\u00f3nico como un medio para la creaci\u00f3n de valor de empresa.<\/li><li>Identificar herramientas ofim\u00e1ticas y canales de distribuci\u00f3n virtual seg\u00fan estrategia de medici\u00f3n y an\u00e1lisis del tr\u00e1fico en la web.<\/li><li>Implementar software para evaluar el rendimiento de las acciones de promoci\u00f3n y campa\u00f1as online en la web, acorde a la estrategia establecida.<\/li><li>Verificar el comportamiento de compra de los clientes en el sitio web, mediante plan de control establecido por la organizaci\u00f3n.<\/li><\/ul><h2>\u00bfA qui\u00e9n va dirigido este curso?<\/h2><p>El curso de Marketing en Redes Sociales e Implantaci\u00f3n del Negocio Electr\u00f3nico est\u00e1 destinado a todas aquellas personas que quieran utilizar las redes sociales y el comercio electr\u00f3nico como un medio para expansi\u00f3n de la empresa.<\/p><h2>Condiciones de compra<\/h2><p>Curso de Marketing en Redes Sociales e Implantaci\u00f3n del Negocio Electr\u00f3nico de<strong> 60\u00a0<\/strong><strong>horas lectivas<\/strong>. Dispondr\u00e1 de 3 meses para finalizar el Curso. El plazo comienza una vez se reciben las claves de acceso.<\/p><ul><li>T\u00edtulo\u00a0acreditativo al finalizar el curso.<\/li><li>Compatible con cualquier sistema operativo y dispositivos m\u00f3viles.<\/li><li>Modalidad 100% online.<\/li><\/ul><p>Recibir\u00e1 las claves de acceso a la plataforma en 24\/48 horas. Compruebe la bandeja de SPAM. En caso de no recibir las claves escriba a <a href=\"mailto:info@efem.es\">info@efem.es<\/a><\/p>                    <\/div>\n\t\t        \n                    <div id=\"temario-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"temario-tab\">\n\t\t\t\t        <h2>Marketing en Redes Sociales<\/h5><p><strong>Consideraciones generales<\/strong><\/p><ul><li>Definici\u00f3n de Redes Sociales<\/li><li>Concepto de marketing-mix<\/li><li>Integraci\u00f3n de las Redes Sociales<\/li><li>Tipos de Redes Sociales<\/li><li>Bases del marketing en las Redes Sociales<\/li><li>Cuestionario: Consideraciones generales<\/li><\/ul><p><strong>Organizaci\u00f3n del trabajo en Redes Sociales<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Escuchar<\/li><li>Planificar la estrategia<\/li><li>Plan de Social Media Marketing de empresa<\/li><li>Crear compromiso<\/li><li>Medir y evaluar<\/li><li>Definir una rutina<\/li><li>Cuestionario: Organizaci\u00f3n del trabajo en Redes Sociales<\/li><\/ul><p><strong>Medici\u00f3n de la estrategia en Redes Sociales<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Etapas medici\u00f3n redes sociales<\/li><li>Monitorizaci\u00f3n<\/li><li>Plan de contingencia<\/li><li>Herramientas para el an\u00e1lisis del Social Media<\/li><li>Cuestionario: Medici\u00f3n de la Estrategia en Redes Sociales<\/li><\/ul><p><strong>Uso de las principales Redes Sociales<\/strong><\/p><ul><li>Facebook<\/li><li>Twitter<\/li><li>Video marketing en YouTube<\/li><li>Estrategias en YouTube para generar tr\u00e1fico en su p\u00e1gina web<\/li><li>Linkedin<\/li><li>Instagram<\/li><li>Pinterest<\/li><li>Cuestionario: Uso de las principales Redes Sociales<\/li><\/ul><p><strong>Valoraci\u00f3n de los contactos en las Redes Sociales<\/strong><\/p><ul><li>Cu\u00e1nto vale cada fan de la p\u00e1gina Facebook<\/li><li>Cu\u00e1nto vale cada seguidor de Twitter<\/li><li>Cuestionario: Consideraciones generales<\/li><\/ul><p><strong>La necesidad de crear un blog<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Selecci\u00f3n de la plataforma de blog<\/li><li>Plugins recomendados para usar con Wordpress<\/li><li>Explotaci\u00f3n del blog corporativo<\/li><li>Trucos para potenciar la visibilidad del blog<\/li><li>Cuestionario: La necesidad de crear un blog<\/li><\/ul><p><strong>\u00c9xito y errores en Social Media<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Estrategia de blogging<\/li><li>Presencia en Facebook<\/li><li>Presencia en Twitter<\/li><li>Presencia en YouTube<\/li><li>Resumen caso de \u00e9xito<\/li><li>Errores de gesti\u00f3n de la reputaci\u00f3n en Redes Sociales<\/li><li>Cuestionario: \u00c9xito y errores en Social Media<\/li><\/ul><p><strong>Otras aplicaciones de marketing en Social Media<\/strong><\/p><ul><li>Marketing mobile<\/li><li>Qu\u00e9 es el Marketing viral<\/li><li>C\u00f3mo funciona el Marketing viral<\/li><li>Elementos de una estrategia del Marketing viral<\/li><li>T\u00e9cnicas de Marketing viral<\/li><li>Elementos que componen una campa\u00f1a de Marketing viral<\/li><li>Ingredientes que potencian un mensaje de Marketing viral<\/li><li>C\u00f3mo construir un mensaje viral eficaz<\/li><li>Cuestionario: Otras aplicaciones de marketing en Social Media<\/li><\/ul><p><strong>Community manager<\/strong><\/p><ul><li>Introducci\u00f3n a Community Manager<\/li><li>Social Media Manager<\/li><li>Perfil y funciones espec\u00edficas del Social Media Manager<\/li><li>Community Manager<\/li><li>Perfil y funciones espec\u00edficas del Community Manager<\/li><li>Las 7 Ces del Community Manager<\/li><li>Cuestionario: Community manager<\/li><li>Cuestionario: Cuestionario final<\/li><\/ul><h2>T\u00e9cnicas de marketing<\/h5><p><strong>Condicionantes del marketing<\/strong><\/p><ul><li>Qu\u00e9 es el marketing<\/li><li>El consumidor<\/li><li>La demanda<\/li><li>El comprador<\/li><li>El mercado &#8211; Segmentaci\u00f3n<\/li><li>Marketing-mix<\/li><li>Cuestionario: Condicionantes del Marketing<\/li><\/ul><p><strong>Estudio de mercados<\/strong><\/p><ul><li>Universo y muestra<\/li><li>Selecci\u00f3n del medio<\/li><li>Realizaci\u00f3n y conteo<\/li><li>Interpretaci\u00f3n de la informaci\u00f3n<\/li><li>Par\u00e1metros estad\u00edsticos<\/li><li>Cuestionario: Estudio de mercados<\/li><\/ul><p><strong>El mercado<\/strong><\/p><ul><li>Concepto de producto<\/li><li>Cualidades de los productos<\/li><li>Importancia del conocimiento del producto<\/li><li>Clasificaci\u00f3n de los productos<\/li><li>Ciclo de vida del producto<\/li><li>Reposicionamiento del producto<\/li><li>Obsolescencia planificada<\/li><li>Estacionalidad<\/li><li>Productos diferenciados y de competencia perfecta<\/li><li>Producto puro y producto a\u00f1adido<\/li><li>Competencia directa y producto sustitutivo<\/li><li>La importancia de la marca<\/li><li>Gama y l\u00ednea de producto<\/li><li>Cuestionario: El mercado<\/li><\/ul><p><strong>Pol\u00edtica de productos<\/strong><\/p><ul><li>L\u00ednea y art\u00edculo<\/li><li>Estrategias de marca<\/li><li>Estrategias de empaquetamiento<\/li><li>Posicionamiento estrat\u00e9gico en el mercado<\/li><li>Pol\u00edticas de marketing<\/li><li>Cuestionario: Pol\u00edtica de productos<\/li><\/ul><p><strong>Pol\u00edtica de precios<\/strong><\/p><ul><li>Fijaci\u00f3n de precios<\/li><li>Pol\u00edtica de precios y CVP<\/li><li>T\u00e1cticas de introducci\u00f3n de precios<\/li><li>Descuentos bonificaciones y rappels<\/li><li>Cuestionario: Pol\u00edtica de precios<\/li><\/ul><p><strong>Pol\u00edtica de distribuci\u00f3n<\/strong><\/p><ul><li>Qu\u00e9 es la distribuci\u00f3n<\/li><li>Venta directa<\/li><li>Venta con intermediarios<\/li><li>Canales de distribuci\u00f3n<\/li><li>Tipos de distribuci\u00f3n<\/li><li>Selecci\u00f3n del canal<\/li><li>Distribuci\u00f3n f\u00edsica de mercanc\u00edas<\/li><li>Cuestionario: Pol\u00edtica de distribuci\u00f3n<\/li><\/ul><p><strong>La comunicaci\u00f3n<\/strong><\/p><ul><li>Naturaleza y definici\u00f3n<\/li><li>Tipos de comunicaci\u00f3n<\/li><li>Elementos del proceso de la comunicaci\u00f3n<\/li><li>El proceso de comunicaci\u00f3n<\/li><li>Problemas de la comunicaci\u00f3n<\/li><li>Personalidades de los actores de la comunicaci\u00f3n<\/li><li>Interacci\u00f3n de caracteres<\/li><li>Comportamientos<\/li><li>Las comunicaciones<\/li><li>La comunicaci\u00f3n en la venta<\/li><li>La comunicaci\u00f3n oral<\/li><li>Caracter\u00edsticas de la comunicaci\u00f3n oral<\/li><li>Normas para la comunicaci\u00f3n oral efectiva<\/li><li>Reglas para hablar bien en p\u00fablico<\/li><li>La comunicaci\u00f3n no verbal o lenguaje del cuerpo<\/li><li>Cuestionario: La comunicaci\u00f3n<\/li><\/ul><p><strong>Pol\u00edtica de comunicaci\u00f3n<\/strong><\/p><ul><li>Elementos estrat\u00e9gicos de la pol\u00edtica de comunicaci\u00f3n<\/li><li>Seguimiento de la comunicaci\u00f3n<\/li><li>Presupuesto de comunicaci\u00f3n<\/li><li>Composici\u00f3n de la mezcla de comunicaci\u00f3n<\/li><li>Cuestionario: Pol\u00edtica de comunicaci\u00f3n<\/li><\/ul><p><strong>Publicidad<\/strong><\/p><ul><li>Publicidad<\/li><li>Establecimiento de metas y objetivos<\/li><li>Decisiones respecto al presupuesto<\/li><li>Decisiones respecto al mensaje<\/li><li>Decisiones respecto al medio<\/li><li>Evaluaci\u00f3n y planificaci\u00f3n de la campa\u00f1a<\/li><li>Cuestionario: Publicidad<\/li><\/ul><p><strong>El perfil del vendedor<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Personalidad del vendedor<\/li><li>Clases de vendedores<\/li><li>Los conocimientos del vendedor<\/li><li>Motivaci\u00f3n y destreza<\/li><li>An\u00e1lisis del perfil del vendedor<\/li><li>El papel del vendedor<\/li><li>Cuestionario: El perfil del vendedor<\/li><\/ul><p><strong>La venta como proceso<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>El proceso de compra-venta<\/li><li>El consumidor como sujeto de la venta<\/li><li>El comportamiento del consumidor<\/li><li>Motivaciones de compra-venta<\/li><li>Cuestionario: La venta como proceso<\/li><\/ul><p><strong>Tipolog\u00eda de la venta<\/strong><\/p><ul><li>Tipolog\u00eda seg\u00fan la pasividad &#8211; actividad<\/li><li>Tipolog\u00eda seg\u00fan la presi\u00f3n<\/li><li>Tipolog\u00eda seg\u00fan la implicaci\u00f3n del producto<\/li><li>Tipolog\u00eda seg\u00fan el p\u00fablico y forma de venta<\/li><li>Cuestionario: Tipolog\u00eda de la venta<\/li><\/ul><p><strong>T\u00e9cnicas de ventas<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Fases de la venta<\/li><li>Contacto y presentaci\u00f3n<\/li><li>Sondeo<\/li><li>Argumentaci\u00f3n<\/li><li>La entrevista<\/li><li>Material de apoyo<\/li><li>El cierre de la venta<\/li><li>El seguimiento<\/li><li>Cuestionario: T\u00e9cnicas de venta<\/li><\/ul><p><strong>Estrategia de ventas<\/strong><\/p><ul><li>Previsi\u00f3n de ventas<\/li><li>M\u00e9todo de encuesta de intenci\u00f3n de compra<\/li><li>Presentaci\u00f3n del presupuesto de ventas<\/li><li>Organizaci\u00f3n y estructura de ventas<\/li><li>Personal de ventas<\/li><li>Cuestionario: Estrategia de ventas<\/li><li>Cuestionario: Cuestionario final<\/li><\/ul><h2>Comercio Electr\u00f3nico<\/h5><p><strong>Introducci\u00f3n al comercio electr\u00f3nico<\/strong><\/p><ul><li>Definici\u00f3n<\/li><li>Situaci\u00f3n actual<\/li><li>Comercio electr\u00f3nico contra comercio tradicional<\/li><li>Ventajas e inconvenientes<\/li><li>Cuestionario: Introducci\u00f3n al comercio electr\u00f3nico<\/li><\/ul><p><strong>La cadena de valor en el comercio electr\u00f3nico<\/strong><\/p><ul><li>Definici\u00f3n<\/li><li>Impacto de Internet en la cadena de valor<\/li><li>Herramientas para el intercambio de informaci\u00f3n<\/li><li>Cadena de valor electr\u00f3nica<\/li><li>Cuestionario: La cadena de valor en el comercio electr\u00f3nico<\/li><\/ul><p><strong>Aspectos tecnol\u00f3gicos del comercio electr\u00f3nico<\/strong><\/p><ul><li>IPS &#8211; Internet Service Providers<\/li><li>Estructuras<\/li><li>Contenidos<\/li><li>Distribuci\u00f3n<\/li><li>Otros servicios para intercambiar informaci\u00f3n<\/li><li>Descarga de archivos &#8211; FTP<\/li><li>Cuestionario: Aspectos tecnol\u00f3gicos del comercio electr\u00f3nico<\/li><\/ul><p><strong>El comercio electr\u00f3nico entre empresas B2B<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Mercados B2B<\/li><li>Pasos b\u00e1sicos de la transacci\u00f3n comercial<\/li><li>Ejemplos de mercado B2B<\/li><li>Servicios que ofrecen las plataformas B2B<\/li><li>Cuestionario: El comercio electr\u00f3nico entre empresas B2B<\/li><\/ul><p><strong>El comercio electr\u00f3nico empresas-cliente B2C<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Mercados B2C<\/li><li>Crear una tienda virtual<\/li><li>Cuestionario: El comercio electr\u00f3nico empresa-cliente B2C<\/li><\/ul><p><strong>E-comercio al servicio de la gesti\u00f3n empresarial<\/strong><\/p><ul><li>Introducci\u00f3n e-commerce<\/li><li>Evoluci\u00f3n del comercio electr\u00f3nico en las empresas<\/li><li>Gesti\u00f3n en los diferentes departamentos<\/li><li>Cuestionario: E-comercio al servicio de la gesti\u00f3n empresarial<\/li><\/ul><p><strong>T\u00e9cnicas de Marketing en Internet<\/strong><\/p><ul><li>Introducci\u00f3n t\u00e9cnicas<\/li><li>Planificaci\u00f3n del e-marketing<\/li><li>T\u00e9cnicas para la personalizaci\u00f3n<\/li><li>T\u00e9cnicas para la publicidad<\/li><li>T\u00e9cnicas para la fidelizaci\u00f3n<\/li><li>El \u00e9xito online es cuantificable &#8211; indicadores de \u00e9xito<\/li><li>Las expectativas de tus clientes<\/li><li>El factor clave del \u00e9xito &#8211; la diferencia es lo que cuenta<\/li><li>Usabilidad<\/li><li>Confianza y seguridad<\/li><li>Marketing y ventas<\/li><li>Servicio al cliente<\/li><li>Cuestionario: T\u00e9cnicas de marketing en Internet<\/li><\/ul><p><strong>Atenci\u00f3n al cliente<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Atenci\u00f3n al cliente en la etapa de precompra<\/li><li>Atenci\u00f3n al cliente en la etapa de compra<\/li><li>Atenci\u00f3n al cliente &#8211; servicio posventa<\/li><li>Ejemplo de atenci\u00f3n al cliente<\/li><li>Cuestionario: Atenci\u00f3n al cliente<\/li><\/ul><p><strong>Seguridad en las transacciones<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Protocolo TLS<\/li><li>Funcionamiento del protocolo TLS<\/li><li>Aplicaciones del protocolo TLS<\/li><li>Implementaci\u00f3n del protocolo TLS<\/li><li>Protocolo SET &#8211; Secure Electronic Transaction<\/li><li>Pasos de una transacci\u00f3n SET<\/li><li>Criptograf\u00eda<\/li><li>Otros sistemas de protecci\u00f3n<\/li><li>Cuestionario: Seguridad en las transacciones<\/li><\/ul><p><strong>Medios de pago y procesos de cobro<\/strong><\/p><ul><li>Introducci\u00f3n pagos y cobros<\/li><li>Pago con tarjeta &#8211; TPV Virtual<\/li><li>Pago directo con tarjeta<\/li><li>Dinero electr\u00f3nico o eCash<\/li><li>CYBERCASH<\/li><li>Otras formas de pago<\/li><li>Cuestionario: Medios de pago y procesos de cobro.<\/li><\/ul><p><strong>Log\u00edstica y distribuci\u00f3n<\/strong><\/p><ul><li>Introducci\u00f3n log\u00edstica<\/li><li>Nuevos servicios<\/li><li>Cuestionario: Log\u00edstica y distribuci\u00f3n<\/li><\/ul><p><strong>Consideraciones jur\u00eddicas y legales<\/strong><\/p><ul><li>Introducci\u00f3n<\/li><li>Ley de protecci\u00f3n de datos de car\u00e1cter personal<\/li><li>Legislaci\u00f3n sobre propiedad intelectual<\/li><li>Contrataci\u00f3n electr\u00f3nica &#8211; la LSSICE<\/li><li>Aspectos m\u00e1s relevantes de la LSSICE<\/li><li>La firma electr\u00f3nica<\/li><li>Cuestionario: Consideraciones jur\u00eddicas y legales<\/li><\/ul><p><strong>Perspectivas del comercio electr\u00f3nico<\/strong><\/p><ul><li>Situaci\u00f3n actual<\/li><li>Perspectivas<\/li><li>Amenazas existentes en el comercio electr\u00f3nico<\/li><li>Sellos de confianza<\/li><li>D\u00f3nde y c\u00f3mo reclamar si la compra no es satisfactoria<\/li><li>Caso pr\u00e1ctico &#8211; Ejemplo de \u00e9xito<\/li><li>Cuestionario: Perspectivas para el comercio electr\u00f3nico.<\/li><li>Cuestionario: Cuestionario final<\/li><\/ul>                    <\/div>\n\t\t        \n                    <div id=\"solicita-informacin-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"solicita-informacin-tab\">\n\t\t\t\t        <style>.elementor-61645 .elementor-element.elementor-element-1841047{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;}.elementor-61645 .elementor-element.elementor-element-391a7c0{text-align:center;}.elementor-61645 .elementor-element.elementor-element-391a7c0 .elementor-heading-title{font-size:22px;font-weight:700;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-field-group{padding-right:calc( 10px\/2 );padding-left:calc( 10px\/2 );margin-bottom:10px;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-form-fields-wrapper{margin-left:calc( -10px\/2 );margin-right:calc( -10px\/2 );margin-bottom:-10px;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-field-group.recaptcha_v3-bottomleft, .elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-field-group.recaptcha_v3-bottomright{margin-bottom:0;}body.rtl .elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-labels-inline .elementor-field-group > label{padding-left:0px;}body:not(.rtl) .elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-labels-inline .elementor-field-group > label{padding-right:0px;}body .elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-labels-above .elementor-field-group > label{padding-bottom:0px;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-field-type-html{padding-bottom:0px;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-field-group .elementor-field:not(.elementor-select-wrapper){background-color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-field-group .elementor-select-wrapper select{background-color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-button{font-size:27px;}.elementor-61645 .elementor-element.elementor-element-d96bacf .e-form__buttons__wrapper__button-next{background-color:#0075C9;color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-button[type=\"submit\"]{background-color:#0075C9;color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-button[type=\"submit\"] svg *{fill:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .e-form__buttons__wrapper__button-previous{color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .e-form__buttons__wrapper__button-next:hover{color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-button[type=\"submit\"]:hover{color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .elementor-button[type=\"submit\"]:hover svg *{fill:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf .e-form__buttons__wrapper__button-previous:hover{color:#ffffff;}.elementor-61645 .elementor-element.elementor-element-d96bacf{--e-form-steps-indicators-spacing:20px;--e-form-steps-indicator-padding:30px;--e-form-steps-indicator-inactive-secondary-color:#ffffff;--e-form-steps-indicator-active-secondary-color:#ffffff;--e-form-steps-indicator-completed-secondary-color:#ffffff;--e-form-steps-divider-width:1px;--e-form-steps-divider-gap:10px;width:var( --container-widget-width, 57% );max-width:57%;--container-widget-width:57%;--container-widget-flex-grow:0;}.elementor-61645 .elementor-element.elementor-element-d96bacf.elementor-element{--align-self:center;}@media(max-width:767px){.elementor-61645 .elementor-element.elementor-element-d96bacf{width:100%;max-width:100%;}}<\/style>\t\t<div data-elementor-type=\"single-post\" data-elementor-id=\"61645\" class=\"elementor elementor-61645\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-1841047 e-flex e-con-boxed e-con e-parent\" data-id=\"1841047\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-391a7c0 elementor-widget elementor-widget-heading\" data-id=\"391a7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">SOLICITA INFORMACI\u00d3N<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1f96f2 elementor-widget elementor-widget-text-editor\" data-id=\"a1f96f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Completa el formulario y en breve nos podremos en contacto contigo v\u00eda email o whatsapp<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d96bacf elementor-button-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-form\" data-id=\"d96bacf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"61645\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"d96bacf\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Curso De Auxiliar De Enfermer\u00eda De Geriatr\u00eda 8 Cr\u00e9ditos ECTS\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"41483\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNombre\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Nombre completo\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_9d297ee elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_9d297ee\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_9d297ee]\" id=\"form-field-field_9d297ee\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Tel\u00e9fono\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_59cce7d elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_59cce7d]\" id=\"form-field-field_59cce7d\" class=\"elementor-field elementor-size-md  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_59cce7d\">Acepto las condiciones legales y la pol\u00edtica de privacidad<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENVIAR<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t                    <\/div>\n\t\t                    <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Las Redes Sociales son un excelente medio para dar a conocer un producto y alcanzar los objetivos de venta marcados en la empresa. Para ello, es fundamental implementar el necio digital en la organizaci\u00f3n.<\/p>\n","protected":false},"featured_media":28619,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[],"product_cat":[113],"product_tag":[43,72],"class_list":["post-28614","product","type-product","status-publish","has-post-thumbnail","product_cat-comercial-y-ventas","product_tag-ecommerce","product_tag-marketing-digital","first","instock","sale","virtual","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/product\/28614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/comments?post=28614"}],"version-history":[{"count":0,"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/product\/28614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/media\/28619"}],"wp:attachment":[{"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/media?parent=28614"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/product_brand?post=28614"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/product_cat?post=28614"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/efem.es\/cursos\/wp-json\/wp\/v2\/product_tag?post=28614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}